{"id":23,"date":"2024-05-11T09:05:51","date_gmt":"2024-05-11T07:05:51","guid":{"rendered":"https:\/\/joschwa.sebi-it.ch\/?page_id=23"},"modified":"2025-10-11T20:03:07","modified_gmt":"2025-10-11T18:03:07","slug":"verein","status":"publish","type":"page","link":"https:\/\/joschwa.ch\/","title":{"rendered":"Verein"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wir sind ein Volleyballverein, gegr\u00fcndet im Jahr 1995, mixed mit Frauen und M\u00e4nnern jeden alters.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Plausch am Bewegen, Spielen und Zusammensein stehen bei uns im Vordergrund.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir trainieren in 2 Gruppen und freuen uns auf neue Mitglieder.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Unsere Trainigszeiten im OZ Degenau:<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Dienstag, 20.00 bis 22.00 Uhr<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">f\u00fcr ambitionierte Spieler\/innen mit Volleyballkenntnissen<br>Wir spielen beim &#171;Zischtigscup&#187; mit, einer regionalen Plausch-Meisterschaft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/vbcaa.ch\/zischtigscup\">Link zur &#171;Zischtigscup&#187;-Webseite.<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Freitag, 19.45 bis 22.00 Uhr<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Training f\u00fcr alle, auch f\u00fcr Einsteiger. Am Freitag steht das Volleyball-Spiel im Vordergrund.<br>Wir nehmen gelegentlich an Plauschturnieren teil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Sommerhalbjahr finden die Trainings bei gutem Wetter auch auf unseren zwei sch\u00f6nen Beachfelder statt. Am Freitag bereits ab 19.00 Uhr, am Dienstag ab 19:30 Uhr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003\u2003 \u2003<br>Sportliche Gr\u00fcsse<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volley Joschwa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Turnhalle Oberstufenzentrum Degenau, Steigstrasse, 9243 Jonschwil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir sind ein Volleyballverein, gegr\u00fcndet im Jahr 1995, mixed mit Frauen und M\u00e4nnern jeden alters. Der Plausch am Bewegen, Spielen und Zusammensein stehen bei uns im Vordergrund. Wir trainieren in 2 Gruppen und freuen uns auf neue Mitglieder. Unsere Trainigszeiten im OZ Degenau: Dienstag, 20.00 bis 22.00 Uhr f\u00fcr ambitionierte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-23","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verein - Volley Joschwa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/joschwa.ch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verein - Volley Joschwa\" \/>\n<meta property=\"og:description\" content=\"Wir sind ein Volleyballverein, gegr\u00fcndet im Jahr 1995, mixed mit Frauen und M\u00e4nnern jeden alters. Der Plausch am Bewegen, Spielen und Zusammensein stehen bei uns im Vordergrund. Wir trainieren in 2 Gruppen und freuen uns auf neue Mitglieder. Unsere Trainigszeiten im OZ Degenau: Dienstag, 20.00 bis 22.00 Uhr f\u00fcr ambitionierte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joschwa.ch\/\" \/>\n<meta property=\"og:site_name\" content=\"Volley Joschwa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-11T18:03:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/joschwa.ch\\\/\",\"url\":\"https:\\\/\\\/joschwa.ch\\\/\",\"name\":\"Verein - Volley Joschwa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joschwa.ch\\\/#website\"},\"datePublished\":\"2024-05-11T07:05:51+00:00\",\"dateModified\":\"2025-10-11T18:03:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/joschwa.ch\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/joschwa.ch\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/joschwa.ch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/joschwa.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/joschwa.ch\\\/#website\",\"url\":\"https:\\\/\\\/joschwa.ch\\\/\",\"name\":\"Volley Joschwa\",\"description\":\"dein regionaler Volleyballverein\",\"publisher\":{\"@id\":\"https:\\\/\\\/joschwa.ch\\\/#organization\"},\"alternateName\":\"Volleyballverein in der Ostschweiz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/joschwa.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/joschwa.ch\\\/#organization\",\"name\":\"Volley Joschwa\",\"url\":\"https:\\\/\\\/joschwa.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/joschwa.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/joschwa.sebi-it.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-Joschwa-Logo.png\",\"contentUrl\":\"https:\\\/\\\/joschwa.sebi-it.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-Joschwa-Logo.png\",\"width\":512,\"height\":512,\"caption\":\"Volley Joschwa\"},\"image\":{\"@id\":\"https:\\\/\\\/joschwa.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verein - Volley Joschwa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/joschwa.ch\/","og_locale":"de_DE","og_type":"article","og_title":"Verein - Volley Joschwa","og_description":"Wir sind ein Volleyballverein, gegr\u00fcndet im Jahr 1995, mixed mit Frauen und M\u00e4nnern jeden alters. Der Plausch am Bewegen, Spielen und Zusammensein stehen bei uns im Vordergrund. Wir trainieren in 2 Gruppen und freuen uns auf neue Mitglieder. Unsere Trainigszeiten im OZ Degenau: Dienstag, 20.00 bis 22.00 Uhr f\u00fcr ambitionierte [&hellip;]","og_url":"https:\/\/joschwa.ch\/","og_site_name":"Volley Joschwa","article_modified_time":"2025-10-11T18:03:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/joschwa.ch\/","url":"https:\/\/joschwa.ch\/","name":"Verein - Volley Joschwa","isPartOf":{"@id":"https:\/\/joschwa.ch\/#website"},"datePublished":"2024-05-11T07:05:51+00:00","dateModified":"2025-10-11T18:03:07+00:00","breadcrumb":{"@id":"https:\/\/joschwa.ch\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/joschwa.ch\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/joschwa.ch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/joschwa.ch\/"},{"@type":"ListItem","position":2,"name":"Verein"}]},{"@type":"WebSite","@id":"https:\/\/joschwa.ch\/#website","url":"https:\/\/joschwa.ch\/","name":"Volley Joschwa","description":"dein regionaler Volleyballverein","publisher":{"@id":"https:\/\/joschwa.ch\/#organization"},"alternateName":"Volleyballverein in der Ostschweiz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/joschwa.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/joschwa.ch\/#organization","name":"Volley Joschwa","url":"https:\/\/joschwa.ch\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/joschwa.ch\/#\/schema\/logo\/image\/","url":"https:\/\/joschwa.sebi-it.ch\/wp-content\/uploads\/2024\/05\/cropped-Joschwa-Logo.png","contentUrl":"https:\/\/joschwa.sebi-it.ch\/wp-content\/uploads\/2024\/05\/cropped-Joschwa-Logo.png","width":512,"height":512,"caption":"Volley Joschwa"},"image":{"@id":"https:\/\/joschwa.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/joschwa.ch\/index.php\/wp-json\/wp\/v2\/pages\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joschwa.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/joschwa.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/joschwa.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joschwa.ch\/index.php\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":10,"href":"https:\/\/joschwa.ch\/index.php\/wp-json\/wp\/v2\/pages\/23\/revisions"}],"predecessor-version":[{"id":193,"href":"https:\/\/joschwa.ch\/index.php\/wp-json\/wp\/v2\/pages\/23\/revisions\/193"}],"wp:attachment":[{"href":"https:\/\/joschwa.ch\/index.php\/wp-json\/wp\/v2\/media?parent=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}